{"id":53731,"date":"2026-08-12T12:41:15","date_gmt":"2026-08-12T15:41:15","guid":{"rendered":"https:\/\/eramine.eramet.com\/?p=53731"},"modified":"2026-08-25T12:45:14","modified_gmt":"2026-08-25T15:45:14","slug":"cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza","status":"publish","type":"post","link":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/","title":{"rendered":"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza."},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1468.8px;margin-left: calc(-2% \/ 2 );margin-right: calc(-2% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.47%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.47%;--awb-width-medium:66.666666666667%;--awb-order-medium:0;--awb-spacing-right-medium:1.47%;--awb-spacing-left-medium:1.47%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0.98%;--awb-spacing-left-small:0.98%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><\/div><div class=\"fusion-text fusion-text-2\"><div>\n<p><span lang=\"ES-AR\" data-contrast=\"auto\">A m\u00e1s de\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">3.800 metros sobre el nivel del mar<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">, en el coraz\u00f3n de la\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">Puna salte\u00f1a<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">, se encuentra el\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">Salar Centenario-Ratones<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">, ubicado en el departamento Los Andes, al noroeste de la provincia de Salta. Es un paisaje inmenso donde el viento sopla con fuerza, el aire es seco\u00a0y\u00a0las temperaturas presentan grandes amplitudes t\u00e9rmicas. A pesar de las condiciones extremas, este territorio alberga una biodiversidad \u00fanica, con especies como vicu\u00f1as, flamencos andinos, suris y zorros, que conviven con una vegetaci\u00f3n adaptada a este ambiente de altura.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p><span lang=\"ES-AR\" data-contrast=\"auto\">Este es tambi\u00e9n el hogar de la\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">comunidad Kolla<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">, uno de los pueblos originarios que habita la regi\u00f3n andina desde hace generaciones. Su historia, identidad y forma de comprender el mundo est\u00e1n profundamente ligadas al territorio. Para los pueblos andinos, la relaci\u00f3n con la naturaleza se construye desde el respeto, el equilibrio y la reciprocidad. Los conocimientos, las ceremonias y las tradiciones que a\u00fan hoy conservan forman parte de un valioso patrimonio cultural transmitido de generaci\u00f3n en generaci\u00f3n.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p><span lang=\"ES-AR\" data-contrast=\"auto\">En la tradici\u00f3n andina la Pachamama ocupa un lugar muy importante. La palabra proviene del quechua:\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">\u00abPacha\u00bb<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">\u00a0hace referencia al mundo, al universo, al tiempo y al territorio; mientras que\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">\u00abMama\u00bb<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">\u00a0significa madre.\u00a0Representando\u00a0a la naturaleza como origen y sost\u00e9n de la vida, proveedora del agua\u00a0y los alimentos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p><span lang=\"ES-AR\" data-contrast=\"auto\">Por este motivo, cada\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">1\u00ba de agosto<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">\u00a0se lleva adelante una ceremonia de agradecimiento en la que se ofrecen alimentos, bebidas y otros elementos simb\u00f3licos como muestra de gratitud por lo recibido y para pedir bienestar, salud, prosperidad y abundancia para el nuevo ciclo que comienza. En la tradici\u00f3n andina, agosto es conocido como\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">el mes de la Pachamama<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">, ya que se considera el inicio de un nuevo ciclo para la tierra y las actividades productivas. Si bien el momento m\u00e1s significativo es el primer d\u00eda del mes, las ceremonias y ofrendas suelen extenderse durante todo agosto.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p><span lang=\"ES-AR\" data-contrast=\"auto\">Existen distintas formas de celebrar esta tradici\u00f3n en los Andes, ya que cada comunidad conserva sus propias costumbres. En nuestro caso, acompa\u00f1amos la ceremonia respetando las pr\u00e1cticas de la\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">comunidad Kolla de Santa Rosa de los Pastos Grandes<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">, quienes mantienen viva esta tradici\u00f3n siguiendo los saberes heredados de sus antepasados. Cada paso del ritual, cada ofrenda y cada gesto poseen un significado particular y reflejan el profundo v\u00ednculo entre las personas y la naturaleza.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p><span lang=\"ES-AR\" data-contrast=\"auto\">Como cada a\u00f1o, en\u00a0Eramet\u00a0Eramine\u00a0tuvimos la oportunidad de compartir esta celebraci\u00f3n junto a la comunidad y las personas que trabajan en Sitio, acompa\u00f1ando una ceremonia que nos permiti\u00f3 conocer m\u00e1s sobre su cultura, sus valores y el significado de esta tradici\u00f3n ancestral. La jornada incluy\u00f3 el tradicional ritual de ofrendas a la Pachamama y un almuerzo con comidas t\u00edpicas especialmente preparado para la ocasi\u00f3n en los comedores de\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">nuestro sitio<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">, generando un espacio de encuentro y reflexi\u00f3n.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p><span lang=\"ES-AR\" data-contrast=\"auto\">Celebrar la Pachamama representa mucho m\u00e1s que participar de una ceremonia.\u00a0Es una oportunidad para reconocer y valorar la riqueza cultural de las comunidades que habitan este territorio, aprender de sus tradiciones y fortalecer el respeto por la identidad local. En\u00a0Eramine\u00a0creemos que construir v\u00ednculos s\u00f3lidos tambi\u00e9n implica comprender,<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">\u00a0aprender\u00a0<\/span><span lang=\"ES-AR\" data-contrast=\"auto\">y acompa\u00f1ar las costumbres de quienes forman parte del lugar donde desarrollamos nuestras actividades, promoviendo una convivencia basada en el respeto, el di\u00e1logo y el reconocimiento mutuo.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":65,"featured_media":53704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[76,92],"class_list":["post-53731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-es","tag-compromisos","tag-comunidades","nature-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza. - Eramet Eramine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza. - Eramet Eramine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/\" \/>\n<meta property=\"og:site_name\" content=\"Eramet Eramine\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-12T15:41:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-25T15:45:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1178\" \/>\n\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mggonzalez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mggonzalez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/\"},\"author\":{\"name\":\"mggonzalez\",\"@id\":\"https:\/\/eramine.eramet.com\/es\/#\/schema\/person\/634a9448e2cae42bcd43a58b91747d65\"},\"headline\":\"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza.\",\"datePublished\":\"2026-08-12T15:41:15+00:00\",\"dateModified\":\"2026-08-25T15:45:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/\"},\"wordCount\":1725,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg\",\"keywords\":[\"Compromisos\",\"Comunidades\"],\"articleSection\":[\"Media\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/\",\"url\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/\",\"name\":\"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza. - Eramet Eramine\",\"isPartOf\":{\"@id\":\"https:\/\/eramine.eramet.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg\",\"datePublished\":\"2026-08-12T15:41:15+00:00\",\"dateModified\":\"2026-08-25T15:45:14+00:00\",\"author\":{\"@id\":\"https:\/\/eramine.eramet.com\/es\/#\/schema\/person\/634a9448e2cae42bcd43a58b91747d65\"},\"breadcrumb\":{\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#primaryimage\",\"url\":\"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg\",\"contentUrl\":\"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg\",\"width\":1178,\"height\":663},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eramine.eramet.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eramine.eramet.com\/es\/#website\",\"url\":\"https:\/\/eramine.eramet.com\/es\/\",\"name\":\"Eramet Eramine\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eramine.eramet.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eramine.eramet.com\/es\/#\/schema\/person\/634a9448e2cae42bcd43a58b91747d65\",\"name\":\"mggonzalez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eramine.eramet.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1fb4e959401c1de369824dc63c7f2526?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1fb4e959401c1de369824dc63c7f2526?s=96&d=mm&r=g\",\"caption\":\"mggonzalez\"},\"url\":\"https:\/\/eramine.eramet.com\/es\/author\/mggonzalez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza. - Eramet Eramine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/","og_locale":"es_ES","og_type":"article","og_title":"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza. - Eramet Eramine","og_url":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/","og_site_name":"Eramet Eramine","article_published_time":"2026-08-12T15:41:15+00:00","article_modified_time":"2026-08-25T15:45:14+00:00","og_image":[{"width":1178,"height":663,"url":"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg","type":"image\/jpeg"}],"author":"mggonzalez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mggonzalez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#article","isPartOf":{"@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/"},"author":{"name":"mggonzalez","@id":"https:\/\/eramine.eramet.com\/es\/#\/schema\/person\/634a9448e2cae42bcd43a58b91747d65"},"headline":"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza.","datePublished":"2026-08-12T15:41:15+00:00","dateModified":"2026-08-25T15:45:14+00:00","mainEntityOfPage":{"@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/"},"wordCount":1725,"commentCount":0,"image":{"@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#primaryimage"},"thumbnailUrl":"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg","keywords":["Compromisos","Comunidades"],"articleSection":["Media"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/","url":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/","name":"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza. - Eramet Eramine","isPartOf":{"@id":"https:\/\/eramine.eramet.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#primaryimage"},"image":{"@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#primaryimage"},"thumbnailUrl":"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg","datePublished":"2026-08-12T15:41:15+00:00","dateModified":"2026-08-25T15:45:14+00:00","author":{"@id":"https:\/\/eramine.eramet.com\/es\/#\/schema\/person\/634a9448e2cae42bcd43a58b91747d65"},"breadcrumb":{"@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#primaryimage","url":"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg","contentUrl":"https:\/\/eramine.eramet.com\/wp-content\/uploads\/sites\/23\/2026\/08\/pachamama_16x9.jpg","width":1178,"height":663},{"@type":"BreadcrumbList","@id":"https:\/\/eramine.eramet.com\/es\/media-es\/cada-agosto-la-celebracion-de-la-pachamama-invita-a-reconocer-el-valor-de-una-tradicion-ancestral-que-une-cultura-territorio-y-naturaleza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eramine.eramet.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cada agosto, la celebraci\u00f3n de la Pachamama invita a reconocer el valor de una tradici\u00f3n ancestral que une cultura, territorio y naturaleza."}]},{"@type":"WebSite","@id":"https:\/\/eramine.eramet.com\/es\/#website","url":"https:\/\/eramine.eramet.com\/es\/","name":"Eramet Eramine","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eramine.eramet.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/eramine.eramet.com\/es\/#\/schema\/person\/634a9448e2cae42bcd43a58b91747d65","name":"mggonzalez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eramine.eramet.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1fb4e959401c1de369824dc63c7f2526?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1fb4e959401c1de369824dc63c7f2526?s=96&d=mm&r=g","caption":"mggonzalez"},"url":"https:\/\/eramine.eramet.com\/es\/author\/mggonzalez\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/posts\/53731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/comments?post=53731"}],"version-history":[{"count":1,"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/posts\/53731\/revisions"}],"predecessor-version":[{"id":53735,"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/posts\/53731\/revisions\/53735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/media\/53704"}],"wp:attachment":[{"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/media?parent=53731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/categories?post=53731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eramine.eramet.com\/es\/wp-json\/wp\/v2\/tags?post=53731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}